{"id":3097362,"date":"2025-02-10T12:21:00","date_gmt":"2025-02-10T12:21:00","guid":{"rendered":"https:\/\/www.clicdata.com\/automatizacion-y-alertas\/"},"modified":"2025-12-02T10:34:58","modified_gmt":"2025-12-02T10:34:58","slug":"automatizacion-y-alertas","status":"publish","type":"page","link":"https:\/\/www.clicdata.com\/es\/plataforma\/automatizacion-y-alertas\/","title":{"rendered":"Automatizaci\u00f3n y Alertas"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":3097381,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Software de Automatizaci\u00f3n de Datos: Datos y Alertas en Tiempo Real | ClicData","_seopress_titles_desc":"Automatiza los flujos de trabajo de datos, las alertas y las sincronizaciones con el software de automatizaci\u00f3n de datos ClicData. Reduce las tareas manuales y responde a las perspectivas al instante. ","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-3097362","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/pages\/3097362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/comments?post=3097362"}],"version-history":[{"count":1,"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/pages\/3097362\/revisions"}],"predecessor-version":[{"id":3097387,"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/pages\/3097362\/revisions\/3097387"}],"up":[{"embeddable":true,"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/pages\/3097381"}],"wp:attachment":[{"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/media?parent=3097362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}