{"id":3100517,"date":"2024-10-21T09:17:54","date_gmt":"2024-10-21T09:17:54","guid":{"rendered":"https:\/\/www.clicdata.com\/dashboards\/analitica-laboral\/"},"modified":"2025-09-02T14:24:45","modified_gmt":"2025-09-02T14:24:45","slug":"analitica-laboral","status":"publish","type":"dashboard","link":"https:\/\/www.clicdata.com\/es\/dashboards\/analitica-laboral\/","title":{"rendered":"Anal\u00edtica laboral"},"content":{"rendered":"<p>Los datos procedentes de m\u00faltiples fuentes se combinan para medir el rendimiento de la organizaci\u00f3n en la asistencia sanitaria con respecto a los objetivos departamentales, con capacidad para identificar r\u00e1pidamente las desviaciones y profundizar en esos departamentos para determinar las causas profundas.<\/p>\n<p>Al analizar tus datos brutos y aumentarlos con nuestro Motor de Conocimiento, la HPA convierte tus ingentes cantidades de datos en informaci\u00f3n procesable, lo que conduce a mejoras organizativas y ventajas competitivas.<\/p>\n","protected":false},"featured_media":3100518,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Sanidad: Cuadro de mando de anal\u00edtica laboral | ClicData","_seopress_titles_desc":"En sanidad, Labor Analytics mide la utilizaci\u00f3n organizativa de la mano de obra bas\u00e1ndose en la actividad\/vol\u00famenes asistenciales y compar\u00e1ndola con los objetivos establecidos.","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"role":[100615],"sector":[100616],"class_list":["post-3100517","dashboard","type-dashboard","status-publish","has-post-thumbnail","hentry","role-operations-es","sector-consultingadvisory-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/dashboard\/3100517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/dashboard"}],"about":[{"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/types\/dashboard"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/media\/3100518"}],"wp:attachment":[{"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/media?parent=3100517"}],"wp:term":[{"taxonomy":"role","embeddable":true,"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/role?post=3100517"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/sector?post=3100517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}