{"id":3099657,"date":"2024-10-28T08:40:46","date_gmt":"2024-10-28T08:40:46","guid":{"rendered":"https:\/\/www.clicdata.com\/connectors\/ftp\/"},"modified":"2024-10-28T08:40:46","modified_gmt":"2024-10-28T08:40:46","slug":"ftp","status":"publish","type":"connector","link":"https:\/\/www.clicdata.com\/es\/connectors\/ftp\/","title":{"rendered":"FTP"},"content":{"rendered":"<p>Automatiza la elaboraci\u00f3n de informes sobre datos que se encuentran en tu port\u00e1til o en servidores internos utilizando el protocolo FTP y ClicData.<\/p>\n","protected":false},"featured_media":3099658,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Informes automatizados con FTP y ClicData","_seopress_titles_desc":"ClicData te permite automatizar la importaci\u00f3n de datos a trav\u00e9s del protocolo FTP y actualizar los cuadros de mando con los datos m\u00e1s actualizados","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"connector-type":[100651],"class_list":["post-3099657","connector","type-connector","status-publish","has-post-thumbnail","hentry","connector-type-files-storage-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/connector\/3099657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/connector"}],"about":[{"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/types\/connector"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/media\/3099658"}],"wp:attachment":[{"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/media?parent=3099657"}],"wp:term":[{"taxonomy":"connector-type","embeddable":true,"href":"https:\/\/www.clicdata.com\/es\/wp-json\/wp\/v2\/connector-type?post=3099657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}